{"id":5561,"date":"2023-11-09T15:39:38","date_gmt":"2023-11-09T14:39:38","guid":{"rendered":"https:\/\/certoplast.com\/infopoint\/notizie\/"},"modified":"2025-04-07T11:21:59","modified_gmt":"2025-04-07T09:21:59","slug":"notizie","status":"publish","type":"page","link":"https:\/\/certoplast.com\/it\/infopoint\/notizie\/","title":{"rendered":"Notizie"},"content":{"rendered":"\r\n\t\t\t       \r\n            \r\n            <div class=\"hero hero-0a868995 full\">\r\n\t\t\t\t\t\t\t\t<div class=\"acf-innerblocks-container\">\n\r\n\t\t\t       \r\n                    \r\n            <div class=\"hero-slide hero-slide-b95cdde3 is-style-image\">\r\n\t\t\t\t<div class=\"hero-canvas\">\r\n\t\t\t\t\t<div class=\"hero-subheadline\">Informazioni attuali<\/div>\t\t\t\t\t<h1 class=\"hero-headline\">Notizie<\/h1>\t\t\t\t<\/div>\r\n\t\t\t\t<div class=\"hero-media hero-media-image\"><img loading=\"lazy\" decoding=\"async\" width=\"1920\" height=\"519\" src=\"https:\/\/certoplast.com\/wp-content\/uploads\/certoplast-header-infopoint.jpg\" class=\"attachment-full size-full\" alt=\"\" srcset=\"https:\/\/certoplast.com\/wp-content\/uploads\/certoplast-header-infopoint.jpg 1920w, https:\/\/certoplast.com\/wp-content\/uploads\/certoplast-header-infopoint-300x81.jpg 300w, https:\/\/certoplast.com\/wp-content\/uploads\/certoplast-header-infopoint-1024x277.jpg 1024w, https:\/\/certoplast.com\/wp-content\/uploads\/certoplast-header-infopoint-768x208.jpg 768w, https:\/\/certoplast.com\/wp-content\/uploads\/certoplast-header-infopoint-1536x415.jpg 1536w\" sizes=\"auto, (max-width: 1920px) 100vw, 1920px\" \/><\/div>            <\/div>\r\n\t\t\t\t\r\n            \r\n\t\t\t\r\n        \r\n            \n<\/div>\r\n\t\t\t\t\t\t\t\t\r\n\t\t\t\t\t\t\t<\/div>\r\n\t\t\t\t\r\n\t\t\t\r\n\t\t\t        \r\n            <section class=\"gb-container gb-container-65bb36d5 gb-container-default\">\n<div class=\"gb-container gb-container-38c5919d\">\n<div class=\"gb-grid-wrapper gb-grid-wrapper-52375aca\">\n<div class=\"gb-grid-column gb-grid-column-52b2ce36\"><div class=\"gb-container gb-container-52b2ce36\">\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h1 class=\"headline\" style=\"color:\">Le nostre<strong> notizie<\/strong><\/h1><\/div>\n\n\n\n<p>Sempre aggiornati: Qui la informiamo sugli sviluppi attuali e sui nuovi prodotti.<\/p>\n\n<\/div><\/div>\n\n<div class=\"gb-grid-column gb-grid-column-57c7c1b7\"><div class=\"gb-container gb-container-57c7c1b7\" data-aos=\"fade-up\" data-aos-delay=\"250\">\n\n\t\t\t\t\t\t\n\t\t\t\n\n\t\t\t\n            <div class=\"grid grid-a82047ab grid-post grid-columns-2\">\n\t\t\t\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"grid-group grid-group-0\">\n\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"grid-inner \">\n\t\t\t\t\t\t\t\t\t\t\t\t\t\t\t<div class=\"grid-item\">\n\t\t\t\t\t\t\t\t\t \n\t\t\t<div class=\"card card-post card-post-5748\">\n\t\t\t\t<div class=\"card-media\"><img loading=\"lazy\" decoding=\"async\" width=\"800\" height=\"800\" src=\"https:\/\/certoplast.com\/wp-content\/uploads\/was-unsere-welt-zusammenhaelt.jpg\" class=\"attachment-square size-square\" alt=\"\" srcset=\"https:\/\/certoplast.com\/wp-content\/uploads\/was-unsere-welt-zusammenhaelt.jpg 800w, https:\/\/certoplast.com\/wp-content\/uploads\/was-unsere-welt-zusammenhaelt-300x300.jpg 300w, https:\/\/certoplast.com\/wp-content\/uploads\/was-unsere-welt-zusammenhaelt-150x150.jpg 150w, https:\/\/certoplast.com\/wp-content\/uploads\/was-unsere-welt-zusammenhaelt-768x768.jpg 768w\" sizes=\"auto, (max-width: 800px) 100vw, 800px\" \/><\/div>\t\t\t\t<div class=\"card-content\">\n\t\t\t\t\t<div class=\"card-inner\">\n\t\t\t\t\t\t<span class=\"card-headline headline is-h3\">Ci\u00f2 che tiene insieme il nostro mondo<\/span><div class=\"card-copy\">Gli adesivi e i sigillanti sono la forza nascosta che tiene insieme il nostro mondo. Scopra subito il film d&#8217;immagine sugli adesivi e i sigillanti dell&#8217;Industrieverband Klebstoffe e.V.. <\/div>\t\t\t\t\t<\/div>\n\n\t\t\t\t\t<div class=\"card-action\"><div class=\"gb-buttons\"><a class=\"gb-button gb-button-blau-gradient\" href=\"https:\/\/certoplast.com\/it\/aktuelles\/cio-che-tiene-insieme-il-nostro-mondo\/\">Per saperne di pi\u00f9<\/a><\/div><\/div>\t\t\t\t<\/div>\n\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t\t\t            <\/div>\n\t\t\t\n\t\t\t\t\t\t\t\n\t\t\t\n            <!-- end:grid -->\n        \n            \n<\/div><\/div>\n<\/div>\n<\/div>\n<\/section><section class=\"gb-container gb-container-59e08ff4 gb-container-default\" id=\"feed-linkedin\">\n<div class=\"gb-container gb-container-4c1d930b\">\n\n<div class=\"wp-block-pixel-headline headlines is-subheadline-bottom has-text-align-left\"><h2 class=\"headline is-h2\" style=\"color:var(--color-brand)\"><mark style=\"background-color:rgba(0, 0, 0, 0)\" class=\"has-inline-color has-color-text-color\">Noi su<\/mark> LinkedIn<\/h2><\/div>\n\n<\/div>\n\n<div class=\"gb-container gb-container-ce4a494b\">\n<div class=\"juicer-feed\" data-feed-id=\"certoplast-8b7db918-e2dd-4343-8575-735d6b1398c2\"><\/div>\n\n<\/div>\n<\/section>","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":0,"parent":5187,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"_acf_changed":false,"inline_featured_image":false,"footnotes":""},"class_list":["post-5561","page","type-page","status-publish"],"acf":[],"_links":{"self":[{"href":"https:\/\/certoplast.com\/it\/wp-json\/wp\/v2\/pages\/5561","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/certoplast.com\/it\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/certoplast.com\/it\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/certoplast.com\/it\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/certoplast.com\/it\/wp-json\/wp\/v2\/comments?post=5561"}],"version-history":[{"count":1,"href":"https:\/\/certoplast.com\/it\/wp-json\/wp\/v2\/pages\/5561\/revisions"}],"predecessor-version":[{"id":5563,"href":"https:\/\/certoplast.com\/it\/wp-json\/wp\/v2\/pages\/5561\/revisions\/5563"}],"up":[{"embeddable":true,"href":"https:\/\/certoplast.com\/it\/wp-json\/wp\/v2\/pages\/5187"}],"wp:attachment":[{"href":"https:\/\/certoplast.com\/it\/wp-json\/wp\/v2\/media?parent=5561"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}